{"id":2771,"date":"2023-06-14T08:24:09","date_gmt":"2023-06-14T07:24:09","guid":{"rendered":"https:\/\/www.ra-grotha.de\/wordpress\/?p=2771"},"modified":"2024-10-13T15:48:02","modified_gmt":"2024-10-13T14:48:02","slug":"ich-bin-einzelanwalt-was-bedeutet-dies-eigentlich-in-der-praxis","status":"publish","type":"post","link":"https:\/\/www.ra-grotha.de\/wordpress\/2771\/ich-bin-einzelanwalt-was-bedeutet-dies-eigentlich-in-der-praxis\/","title":{"rendered":"Ich bin Einzelanwalt &#8211; was bedeutet dies eigentlich in der Praxis ?"},"content":{"rendered":"\n<p>Ich bin Einzelanwalt &#8211; was bedeutet dies eigentlich in der Praxis ?<\/p>\n\n\n\n<p>Nun, dies bedeutet zun\u00e4chst ganz einfach, dass ich alles allein mache <img loading=\"lazy\" decoding=\"async\" alt=\"\ud83d\ude09\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb0\/1.5\/16\/1f609.png\" width=\"16\" height=\"16\"> . Nat\u00fcrlich tatkr\u00e4ftig unterst\u00fctzt durch meine langj\u00e4hrige Mitarbeiterin, mit der ich mich blind verstehe &#8211; und vernetzt im st\u00e4ndigen Austausch mit Kolleginnen und Kollegen aus dem sozialrechtlichen Bereich.<\/p>\n\n\n\n<p>F\u00fcr Sie als Mandanten bedeutet dies, dass Sie immer durch mich pers\u00f6nlich betreut werden und Sie keine h\u00e4ufig wechselnden <a><\/a>Ansprechpartner haben. Das pers\u00f6nliche Verh\u00e4ltnis zwischen Mandant\/-in und Anwalt ist mir sehr wichtig.<\/p>\n\n\n\n<p>Allerdings bedeutet dies auch, dass wir nicht acht Stunden am Tag telefonisch erreichbar sein k\u00f6nnen. Alle anderen Kan\u00e4le stehen aber jederzeit zur Verf\u00fcgung (auch f\u00fcr einen R\u00fcckrufwunsch), sei es \u00fcber E-Mail, ganz altert\u00fcmlich \u00fcber unseren Anrufbeantworter oder (ganz neu) \u00fcber unsere auf der Website integrierte Chat-Funktion.<\/p>\n\n\n\n<p>Bei Anfragen f\u00fcr neue Mandate nutzen Sie bitte m\u00f6glichst diese Chat-Funktion, dies erleichtert uns die Arbeit sehr.<\/p>\n\n\n\n<p>Einzelanwalt zu sein, heisst auch, dass die zeitlichen Ressourcen begrenzt sind. Zumal ich auch ein buntes Leben neben der Juristerei brauche und habe <img loading=\"lazy\" decoding=\"async\" alt=\"\ud83d\ude43\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t26\/1.5\/16\/1f643.png\" width=\"16\" height=\"16\">.<\/p>\n\n\n\n<p>Ich kann nicht jedes Mandat annehmen. Wir erhalten viele Anfragen, von denen ich nicht wenige ablehnen muss. Zum Beispiel, weil ich ausschlie\u00dflich sozialrechtliche Mandate bearbeite und nichts anderes. Aber auch deshalb, weil ich immer nur so viele Mandate annehme, wie ich auch in angemessener Zeit gut bearbeiten kann.<\/p>\n\n\n\n<p>Es n\u00fctzt niemandem etwas, wenn ein Anwalt ein Mandat \u00fcbernimmt, das er entweder fachlich nicht beherrscht oder f\u00fcr das er eigentlich gar keine freie Zeit hat.<\/p>\n\n\n\n<p>Wenn ich etwas \u00fcbernehme, dann bin ich mit vollem Einsatz f\u00fcr Sie da !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich bin Einzelanwalt &#8211; was bedeutet dies eigentlich in der Praxis ? Nun, dies bedeutet zun\u00e4chst ganz einfach, dass ich alles allein mache . Nat\u00fcrlich tatkr\u00e4ftig unterst\u00fctzt durch meine langj\u00e4hrige Mitarbeiterin, mit der ich mich blind verstehe &#8211; und vernetzt<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2771","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/posts\/2771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2771"}],"version-history":[{"count":2,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/posts\/2771\/revisions"}],"predecessor-version":[{"id":2773,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/posts\/2771\/revisions\/2773"}],"wp:attachment":[{"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/media?parent=2771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/categories?post=2771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/tags?post=2771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}