{"id":2100,"date":"2019-08-13T15:30:17","date_gmt":"2019-08-13T14:30:17","guid":{"rendered":"http:\/\/www.ra-grotha.de\/?p=2100"},"modified":"2019-08-13T15:30:17","modified_gmt":"2019-08-13T14:30:17","slug":"wichtige-ausnahme-vom-zuflussprinzip-jobcenter","status":"publish","type":"post","link":"https:\/\/www.ra-grotha.de\/wordpress\/2100\/wichtige-ausnahme-vom-zuflussprinzip-jobcenter\/","title":{"rendered":"Wichtige Ausnahme vom Zuflussprinzip (Jobcenter) !"},"content":{"rendered":"<p>Im Bereich der Jobcenter-Leistungen gilt grunds\u00e4tzlich das sogenannte Zuflussprinzip. Dies bedeutet, dass Einnahmen grunds\u00e4tzlich in demjenigen Monat als Einkommen anzurechnen sind, in dem sie zuflie\u00dfen.<\/p>\n<p>Beispiel: der Leistungsberechtigte verdient mit seiner beruflichen T\u00e4tigkeit im Juli 500,00 \u20ac. Das Juli-Gehalt wird jedoch erst am 1. August auf seinem Konto gutgeschrieben. Die Anrechnung erfolgt dann nach dem Zuflussprinzip auf die Leistungen des Jobcenter im August, obwohl es im Juli &#8222;verdient&#8220; wurde.<\/p>\n<p>Dieses Zuflussprinzip st\u00f6\u00dft manchmal bei meinen Mandanten auf Unverst\u00e4ndnis, was h\u00e4ufig auch nachvollziehbar ist.<\/p>\n<p>F\u00fcr bestimmte Fallkonstellationen sind jedoch Ausnahmen vom Zuflussprinzip vorgesehen.<\/p>\n<p>Eine wichtige Ausnahme ergibt sich aus einem Urteil des Bundessozialgerichts vom 25.10.2017. Hiernach sind Nachzahlungen von Kinderzuschlag (Familienkasse) abweichend vom tats\u00e4chlichen Zufluss demjenigen Monat als Einkommen zuzurechnen, f\u00fcr den sie erbracht worden sind. Hier ist also gerade nicht entscheidend, wann der Kinderzuschlag ausgezahlt wurde.<\/p>\n<p>Beispiel: f\u00fcr den Monat Mai wird Kinderzuschlag bei der Familienkasse beantragt. Ab Juli werden dann Leistungen beim Jobcenter bezogen. Die Familienkasse ben\u00f6tigt einige Wochen f\u00fcr die Bearbeitung des Antrages und bewilligt im Juli den Kinderzuschlag f\u00fcr den Mai und zahlt diesen dann auch im Juli aus. In diesem Fall darf der Kinderzuschlag keinesfalls als Einkommen beim Jobcenter im Monat Juli angerechnet werden, auch wenn der Zufluss des Geldes in diesem Monat erfolgte.<\/p>\n<p>In der Praxis kommt es trotz des eindeutigen Urteils des Bundessozialgerichts immer wieder vor, dass die Jobcenter dies nicht ber\u00fccksichtigen und Einnahmen aus Kinderzuschlag fehlerhaft als Einkommen anrechnen.<\/p>\n<p>Innerhalb der letzten Tage hatte ich gleich zwei F\u00e4lle dieser Art.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Bereich der Jobcenter-Leistungen gilt grunds\u00e4tzlich das sogenannte Zuflussprinzip. Dies bedeutet, dass Einnahmen grunds\u00e4tzlich in demjenigen Monat als Einkommen anzurechnen sind, in dem sie zuflie\u00dfen. Beispiel: der Leistungsberechtigte verdient mit seiner beruflichen T\u00e4tigkeit im Juli 500,00 \u20ac. Das Juli-Gehalt wird<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-2100","post","type-post","status-publish","format-standard","hentry","category-buergergeld"],"_links":{"self":[{"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/posts\/2100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2100"}],"version-history":[{"count":1,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/posts\/2100\/revisions"}],"predecessor-version":[{"id":2101,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/posts\/2100\/revisions\/2101"}],"wp:attachment":[{"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/media?parent=2100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/categories?post=2100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/tags?post=2100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}