{"id":1992,"date":"2018-11-12T15:16:42","date_gmt":"2018-11-12T14:16:42","guid":{"rendered":"http:\/\/www.ra-grotha.de\/?p=1992"},"modified":"2018-11-12T15:16:42","modified_gmt":"2018-11-12T14:16:42","slug":"ablehnung-der-erwerbsminderungsrente-haeufig-nach-aktenlage","status":"publish","type":"post","link":"https:\/\/www.ra-grotha.de\/wordpress\/1992\/ablehnung-der-erwerbsminderungsrente-haeufig-nach-aktenlage\/","title":{"rendered":"Ablehnung der Erwerbsminderungsrente h\u00e4ufig nach Aktenlage"},"content":{"rendered":"<p>Vergangene Woche erhielt ich in einer Rentenangelegenheit eine gute Nachricht in Form eines Abhilfebescheides. Die Rentenversicherung hatte den Antrag meiner Mandantin auf Gew\u00e4hrung einer Erwerbsminderungsrente abgelehnt. Hiergegen hatten wir Widerspruch erhoben, erfreulicherweise mit Erfolg.<\/p>\n<p>Die Konstellation war so, wie es h\u00e4ufig der Fall ist: die Mandantin erkrankte und bezog zun\u00e4chst f\u00fcr l\u00e4ngere Zeit Krankengeld b<span class=\"text_exposed_show\">ei der gesetzlichen Krankenversicherung. Sie absolvierte dann eine Reha-Ma\u00dfnahme, die jedoch nicht zur Wiedererlangung der Arbeitsf\u00e4higkeit f\u00fchrte. Den darauf folgenden Antrag auf Gew\u00e4hrung der Erwerbsminderungsrente wurde dann durch die Rentenversicherung nach Aktenlage ausschlie\u00dflich auf Basis des Reha-Berichtes abgelehnt.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>Die Entscheidungsgrundlage hierzu bestand einzig und allein aus ein paar angekreuzten Feldern auf einem Vordruck, die au\u00dferdem nicht einmal den Inhalt des Reha-Berichtes widerspiegelten. Diese Dinge pr\u00fcfe ich stets dadurch, dass ich Akteneinsicht in den Verwaltungsvorgang der Beh\u00f6rde beantrage.<\/p>\n<p>Erst im eingeleiteten Widerspruchsverfahren begann die Rentenversicherung damit, den medizinischen Sachverhalt vern\u00fcnftig aufzukl\u00e4ren, nahm Befundberichte der behandelnden \u00c4rzte zur Kenntnis und gab zwei medizinische Sachverst\u00e4ndigengutachten in Auftrag. In diesen Gutachten wurde die Erwerbsminderung dann medizinisch best\u00e4tigt, sodass die Mandantin nun ihre Erwerbsminderungsrente erh\u00e4lt.<\/p>\n<p>In Anbetracht dessen, dass diese Rentenart h\u00e4ufig die wirtschaftliche Existenz der Betroffenen sicherstellt, w\u00e4re eine gr\u00fcndlichere Pr\u00fcfung von Rentenantr\u00e4gen sicherlich w\u00fcnschenswert.<\/p>\n<p>Da dies wohl nur ein frommer Wunsch bleibt, kann ich jedem \u00e4hnlich Betroffenen nur raten, eine ablehnende Entscheidung der Rentenversicherung nicht ungepr\u00fcft hinzunehmen. Dies gilt gleicherma\u00dfen auch f\u00fcr andere sozialrechtliche Beh\u00f6rden (Versorgungsamt, Krankenkasse, Unfallversicherung etc.).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vergangene Woche erhielt ich in einer Rentenangelegenheit eine gute Nachricht in Form eines Abhilfebescheides. Die Rentenversicherung hatte den Antrag meiner Mandantin auf Gew\u00e4hrung einer Erwerbsminderungsrente abgelehnt. Hiergegen hatten wir Widerspruch erhoben, erfreulicherweise mit Erfolg. Die Konstellation war so, wie es<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-1992","post","type-post","status-publish","format-standard","hentry","category-rentenrecht"],"_links":{"self":[{"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/posts\/1992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/comments?post=1992"}],"version-history":[{"count":1,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/posts\/1992\/revisions"}],"predecessor-version":[{"id":1993,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/posts\/1992\/revisions\/1993"}],"wp:attachment":[{"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/media?parent=1992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/categories?post=1992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ra-grotha.de\/wordpress\/wp-json\/wp\/v2\/tags?post=1992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}